{"id":18360,"date":"2025-04-08T13:55:51","date_gmt":"2025-04-08T11:55:51","guid":{"rendered":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/?p=18360"},"modified":"2025-04-08T13:55:51","modified_gmt":"2025-04-08T11:55:51","slug":"un-agneau-a-lecole","status":"publish","type":"post","link":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/2025\/04\/08\/un-agneau-a-lecole\/","title":{"rendered":"Un agneau \u00e0 l&rsquo;\u00e9cole !"},"content":{"rendered":"<p>Depuis d\u00e9but novembre 2024, nous avons 2 moutons au fond de la cour de r\u00e9cr\u00e9ation.<\/p>\n<p>Quelle grande surprise ce lundi 7 avril, de d\u00e9couvrir la naissance d&rsquo;un agneau sur notre terrain !<\/p>\n<p>Reste \u00e0 lui trouver un joli pr\u00e9nom&#8230; A vos suggestions !<\/p>\n<p><iframe loading=\"lazy\" title=\"Agneau 07 04 25\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/PYt34_5lEUE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis d\u00e9but novembre 2024, nous avons 2 moutons au fond de la cour de r\u00e9cr\u00e9ation. Quelle grande surprise ce lundi 7 avril, de d\u00e9couvrir la naissance d&rsquo;un agneau sur notre terrain ! Reste \u00e0 lui trouver un joli pr\u00e9nom&#8230; A vos suggestions !<\/p>\n","protected":false},"author":5,"featured_media":18361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-18360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viedelecole"],"_links":{"self":[{"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/posts\/18360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/comments?post=18360"}],"version-history":[{"count":1,"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/posts\/18360\/revisions"}],"predecessor-version":[{"id":18362,"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/posts\/18360\/revisions\/18362"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/media\/18361"}],"wp:attachment":[{"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/media?parent=18360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/categories?post=18360"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.ecole-saintjoseph-mauleon.fr\/fr\/wp-json\/wp\/v2\/tags?post=18360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}